{"id":54120,"date":"2026-09-02T14:47:01","date_gmt":"2026-09-02T12:47:01","guid":{"rendered":"https:\/\/casaitalia.tv\/canale53\/prodotto\/cm-copriletto-in-fantasia-floreale\/"},"modified":"2026-09-02T14:47:34","modified_gmt":"2026-09-02T12:47:34","slug":"cm-copriletto-in-fantasia-floreale","status":"publish","type":"product","link":"https:\/\/casaitalia.tv\/canale53\/prodotto\/cm-copriletto-in-fantasia-floreale\/","title":{"rendered":"154262"},"content":{"rendered":"<p><b>CASA MANU <\/b>Copriletto in fantasia floreale.<\/p>\n<p><b>Misure: <\/b>160x280cm<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CM Copriletto in fantasia floreale.<\/p>\n","protected":false},"featured_media":1745998,"template":"","meta":{"_acf_changed":false},"pwb-brand":[9225],"product_brand":[],"product_cat":[7656,7646],"product_tag":[],"woo-feed-brand":[],"class_list":["post-54120","product","type-product","status-publish","has-post-thumbnail","pwb-brand-casa-manu","product_cat-arredo-letto-casa-e-cucina-casa-e-cucina","product_cat-casa-e-cucina","pa_colore-arancio","pa_colore-celeste","pa_colore-oro","pa_colore-rosa","first","outofstock","sale","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>154262 - Casa Italia 53<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casaitalia.tv\/canale53\/prodotto\/cm-copriletto-in-fantasia-floreale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"154262 - Casa Italia 53\" \/>\n<meta property=\"og:description\" content=\"CM Copriletto in fantasia floreale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casaitalia.tv\/canale53\/prodotto\/cm-copriletto-in-fantasia-floreale\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa Italia 53\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T12:47:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casaitalia.tv\/canale53\/wp-content\/uploads\/2026\/09\/154-262-arancio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1257\" \/>\n\t<meta property=\"og:image:height\" content=\"870\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/casaitalia.tv\\\/canale53\\\/prodotto\\\/cm-copriletto-in-fantasia-floreale\\\/\",\"url\":\"https:\\\/\\\/casaitalia.tv\\\/canale53\\\/prodotto\\\/cm-copriletto-in-fantasia-floreale\\\/\",\"name\":\"154262 - Casa Italia 53\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casaitalia.tv\\\/canale53\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/casaitalia.tv\\\/canale53\\\/prodotto\\\/cm-copriletto-in-fantasia-floreale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/casaitalia.tv\\\/canale53\\\/prodotto\\\/cm-copriletto-in-fantasia-floreale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/casaitalia.tv\\\/canale53\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/154-262-arancio.jpg\",\"datePublished\":\"2026-09-02T12:47:01+00:00\",\"dateModified\":\"2026-09-02T12:47:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/casaitalia.tv\\\/canale53\\\/prodotto\\\/cm-copriletto-in-fantasia-floreale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/casaitalia.tv\\\/canale53\\\/prodotto\\\/cm-copriletto-in-fantasia-floreale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/casaitalia.tv\\\/canale53\\\/prodotto\\\/cm-copriletto-in-fantasia-floreale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/casaitalia.tv\\\/canale53\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/154-262-arancio.jpg\",\"contentUrl\":\"https:\\\/\\\/casaitalia.tv\\\/canale53\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/154-262-arancio.jpg\",\"width\":1257,\"height\":870},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/casaitalia.tv\\\/canale53\\\/prodotto\\\/cm-copriletto-in-fantasia-floreale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/casaitalia.tv\\\/canale53\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/casaitalia.tv\\\/canale53\\\/shop-di-calzature-e-abbigliamento\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"154262\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/casaitalia.tv\\\/canale53\\\/#website\",\"url\":\"https:\\\/\\\/casaitalia.tv\\\/canale53\\\/\",\"name\":\"Casa Italia 53\",\"description\":\"Il tuo shop online e in tv\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/casaitalia.tv\\\/canale53\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"154262 - Casa Italia 53","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casaitalia.tv\/canale53\/prodotto\/cm-copriletto-in-fantasia-floreale\/","og_locale":"it_IT","og_type":"article","og_title":"154262 - Casa Italia 53","og_description":"CM Copriletto in fantasia floreale.","og_url":"https:\/\/casaitalia.tv\/canale53\/prodotto\/cm-copriletto-in-fantasia-floreale\/","og_site_name":"Casa Italia 53","article_modified_time":"2026-09-02T12:47:34+00:00","og_image":[{"width":1257,"height":870,"url":"https:\/\/casaitalia.tv\/canale53\/wp-content\/uploads\/2026\/09\/154-262-arancio.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/casaitalia.tv\/canale53\/prodotto\/cm-copriletto-in-fantasia-floreale\/","url":"https:\/\/casaitalia.tv\/canale53\/prodotto\/cm-copriletto-in-fantasia-floreale\/","name":"154262 - Casa Italia 53","isPartOf":{"@id":"https:\/\/casaitalia.tv\/canale53\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casaitalia.tv\/canale53\/prodotto\/cm-copriletto-in-fantasia-floreale\/#primaryimage"},"image":{"@id":"https:\/\/casaitalia.tv\/canale53\/prodotto\/cm-copriletto-in-fantasia-floreale\/#primaryimage"},"thumbnailUrl":"https:\/\/casaitalia.tv\/canale53\/wp-content\/uploads\/2026\/09\/154-262-arancio.jpg","datePublished":"2026-09-02T12:47:01+00:00","dateModified":"2026-09-02T12:47:34+00:00","breadcrumb":{"@id":"https:\/\/casaitalia.tv\/canale53\/prodotto\/cm-copriletto-in-fantasia-floreale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casaitalia.tv\/canale53\/prodotto\/cm-copriletto-in-fantasia-floreale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/casaitalia.tv\/canale53\/prodotto\/cm-copriletto-in-fantasia-floreale\/#primaryimage","url":"https:\/\/casaitalia.tv\/canale53\/wp-content\/uploads\/2026\/09\/154-262-arancio.jpg","contentUrl":"https:\/\/casaitalia.tv\/canale53\/wp-content\/uploads\/2026\/09\/154-262-arancio.jpg","width":1257,"height":870},{"@type":"BreadcrumbList","@id":"https:\/\/casaitalia.tv\/canale53\/prodotto\/cm-copriletto-in-fantasia-floreale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casaitalia.tv\/canale53\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/casaitalia.tv\/canale53\/shop-di-calzature-e-abbigliamento\/"},{"@type":"ListItem","position":3,"name":"154262"}]},{"@type":"WebSite","@id":"https:\/\/casaitalia.tv\/canale53\/#website","url":"https:\/\/casaitalia.tv\/canale53\/","name":"Casa Italia 53","description":"Il tuo shop online e in tv","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casaitalia.tv\/canale53\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"immagine_del_prodotto":"https:\/\/casaitalia.tv\/canale53\/wp-content\/uploads\/2026\/09\/154-262-arancio.jpg","prezzi":{"scontato":69,"regolare":108,"corrente":"69"},"brands":[{"id":9225,"name":"CASA MANU","slug":"casa-manu"}],"_links":{"self":[{"href":"https:\/\/casaitalia.tv\/canale53\/wp-json\/wp\/v2\/product\/54120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casaitalia.tv\/canale53\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/casaitalia.tv\/canale53\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casaitalia.tv\/canale53\/wp-json\/wp\/v2\/media\/1745998"}],"wp:attachment":[{"href":"https:\/\/casaitalia.tv\/canale53\/wp-json\/wp\/v2\/media?parent=54120"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/casaitalia.tv\/canale53\/wp-json\/wp\/v2\/pwb-brand?post=54120"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/casaitalia.tv\/canale53\/wp-json\/wp\/v2\/product_brand?post=54120"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/casaitalia.tv\/canale53\/wp-json\/wp\/v2\/product_cat?post=54120"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/casaitalia.tv\/canale53\/wp-json\/wp\/v2\/product_tag?post=54120"},{"taxonomy":"woo-feed-brand","embeddable":true,"href":"https:\/\/casaitalia.tv\/canale53\/wp-json\/wp\/v2\/woo-feed-brand?post=54120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}